{"id":66194,"date":"2026-03-26T10:14:47","date_gmt":"2026-03-26T09:14:47","guid":{"rendered":"https:\/\/www.momenti-casa.it\/tailor-covering\/nature\/pla-15\/"},"modified":"2026-05-05T17:10:12","modified_gmt":"2026-05-05T15:10:12","slug":"pla-15","status":"publish","type":"tailor-covering","link":"https:\/\/www.momenti-casa.it\/en\/tailor-covering\/nature\/pla-15\/","title":{"rendered":"PLA-15"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8841&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; fit_to_container=&#8221;1&#8243; image_object_position=&#8221;center center&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;30&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<a href=\"https:\/\/www.momenti-casa.it\/en\/tailorcovering\/\">Tailor Covering<\/a> \/ <a href=\"https:\/\/www.momenti-casa.it\/en\/tailor-covering\/nature\/\">Nature<\/a> \/ PLA-15[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;150&#8243; top_padding_tablet=&#8221;20&#8243; bottom_padding_tablet=&#8221;140&#8243; top_padding_phone=&#8221;40&#8243; bottom_padding_phone=&#8221;90&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h1>PLA-15<\/h1>\n[\/vc_column_text][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;default&#8221; heading_tag=&#8221;p&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; text_color=&#8221;#11100E&#8221; text_color_hover=&#8221;#7A7A7A&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;<strong>Momenti Lab<\/strong>&#8221; url=&#8221;\/en\/designer\/momenti-lab\/&#8221; text=&#8221;Designer:&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;40&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a03ea9477a2c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a03ea947819d\" data-midnight=\"\" data-column-margin=\"10px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<a class=\"nectar-button large regular extra-color-1 has-icon  regular-button button-configuratore\"  role=\"button\" style=\"margin-right: 20px; margin-bottom: 20px; color: #FFFFFF; background-color: #11100E;\"  href=\"\/en\/configure\/\" data-color-override=\"#11100E\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Configure<\/span><i style=\"color: #FFFFFF;\"  class=\"fa fa-sliders\"><\/i><\/a><a class=\"nectar-button large see-through extra-color-1 has-icon\"  role=\"button\" style=\"\"  href=\"\/en\/contacts\/\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Request information<\/span><i  class=\"fa fa-info-circle\"><\/i><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"toggles \" data-br=\"\" data-starting=\"default\" data-style=\"minimal\"><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>Materials<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>We use the finest materials for decorative wall coverings, ranging from plain or canvas-effect wallpapers to fibreglass options that are also ideal for outdoor use; alternatively, you can opt for sound-absorbing materials.<\/p>\n<p><strong>Grainy Wallpaper<\/strong><br \/>\nA wallpaper fabric for decorative wall coverings with a canvas-effect texture.<\/p>\n<p><strong>Canvas Royal Wallpaper<\/strong><br \/>\nWallpaper fabric for decorative wall coverings with a textured linen-effect finish; non-woven backing.<\/p>\n<p><strong>Light Eco Fiber<\/strong><br \/>\nDecorative technical non-woven fabric made from glass fibre.\u2028Tecno Fiber\u2028Decorative technical fabric made from glass fibre.<\/p>\n<p><strong>Tecno Fiber<br \/>\n<\/strong>Decorative technical covering fabric in fiberglass.<strong><br \/>\n<\/strong><\/p>\n<p><strong>Acoustic Fiber<\/strong><br \/>\nTrevira CS technical upholstery fabric with a honeycomb structure for sound absorption.<\/p>\n<p><strong>Sound-Absorbing Tecno Fiber<\/strong><br \/>\nA decorative technical fabric made of fibreglass, bonded to a special honeycomb layer designed for sound absorption.<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"\/en\/materials\/\"><strong>Discover all the available materials<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>Samples<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>You can request samples with artistic prints for various materials.<\/p>\n<p>Dimensions <strong>50 x 50 cm<\/strong><br \/>\nScale <strong>1:1<\/strong><br \/>\nProduction time <strong>7\u201315 working days<\/strong><br \/>\n<strong>Excluding delivery costs<\/strong><br \/>\n<strong>The cost of the selected sample will be credited upon order confirmation<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"\/en\/contacts\"><strong>Contact us here<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>Catalogue<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>A selection of all our collections.<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"\/en\/catalogues\/\"><strong>Download catalogue<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>How to purchase<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>You can make purchases through our sales team. Our staff are on hand to provide bespoke quotes, assist with invoicing or answer any enquiries you may have.<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"\/en\/contacts\/\"><strong>Contact us here<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>Installation service<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>Wallpaper should be installed by qualified professionals. If you do not have anyone in mind, we can recommend qualified professionals in your area.<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"\/en\/contacts\/\"><strong>Contact us here<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>Product information sheet and assembly instructions<\/a><\/h3><div><div class=\"inner-toggle-wrap\"><div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"https:\/\/areariservata.momenti-casa.it\/en\/\"><strong>Download the product sheet<\/strong><\/a><\/span><\/p><\/div><div class=\"divider-wrap height_tablet_25px height_phone_25px \" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"https:\/\/areariservata.momenti-casa.it\/en\/\"><strong>Download assembly instructions<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><div class=\"toggle extra-color-1\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus\"><\/i>High-resolution images<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>Download the high-resolution images and use them in your projects<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><a target=\"_blank\" class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"https:\/\/areariservata.momenti-casa.it\/en\/\"><strong>Download images<\/strong><\/a><\/span><\/p><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;30&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>GRAPHICS<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;100&#8243; bottom_padding_tablet=&#8221;80&#8243; bottom_padding_phone=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8843&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a03ea947bda0\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row  top_padding_tablet_150px top_padding_phone_80px\"  style=\"padding-top: 250px; padding-bottom: 30px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<h2>CATALOGUE<\/h2>\n<\/div>\n\n\n\n<div class=\"divider-wrap height_tablet_40px height_phone_30px \" data-alignment=\"default\"><div style=\"height: 60px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a03ea947c1b2\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"357\" width=\"476\" data-animation=\"none\" src=\"https:\/\/www.momenti-casa.it\/wp-content\/uploads\/2026\/02\/collections-tailor-covering-catalogue.jpg\" alt=\"\" srcset=\"https:\/\/www.momenti-casa.it\/wp-content\/uploads\/2026\/02\/collections-tailor-covering-catalogue.jpg 476w, https:\/\/www.momenti-casa.it\/wp-content\/uploads\/2026\/02\/collections-tailor-covering-catalogue-300x225.jpg 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" title=\"\">\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-cta  text_hover_color_7A7A7A alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit has-icon \" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"--nectar-text-color: #11100E; --nectar-button-color: var(--nectar-default); --nectar-text-color-hover: #7A7A7A; --nectar-icon-gap: 10px; \"><p style=\"color: #11100E;\"> <span class=\"link_wrap\" ><i class=\"fa fa-arrow-right\"><\/i><a  class=\"link_text\" style=\"border-color: #11100E;\" role=\"button\" href=\"\/en\/catalogues\/\">Download catalogue<\/a><\/span><\/p><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;250&#8243; bottom_padding=&#8221;180&#8243; top_padding_tablet=&#8221;100&#8243; top_padding_phone=&#8221;10&#8243; bottom_padding_phone=&#8221;80&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>FROM THE SAME ARTIST<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60&#8243;][nectar_post_grid post_type=&#8221;custom&#8221; cpt_name=&#8221;tailor-covering&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;none&#8221; exclude_current_post=&#8221;yes&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;10px&#8221; grid_item_height=&#8221;30vh&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;large&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;default&#8221; image_loading=&#8221;default&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h4&#8243; heading_tag_render=&#8221;h4&#8243; category_position=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;animated_underline&#8221; border_radius=&#8221;none&#8221; posts_per_page=&#8221;6&#8243; display_type=&#8221;grid&#8221; custom_font_size=&#8221;26px&#8221; custom_query_tax=&#8221;110&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"Tailor Covering \/ Nature \/ PLA-15 PLA-15 Designer: Momenti Lab ConfigureRequest information Materials We use the finest materials for decorative wall coverings, ranging from plain or canvas-effect wallpapers to fibreglass...","protected":false},"author":4,"featured_media":8846,"parent":11566,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"collezione":[],"linea":[71],"materiale":[],"designer":[217],"class_list":{"0":"post-66194","1":"tailor-covering","2":"type-tailor-covering","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"linea-nature","8":"designer-momenti-lab"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/tailor-covering\/66194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/tailor-covering"}],"about":[{"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/types\/tailor-covering"}],"author":[{"embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":4,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/tailor-covering\/66194\/revisions"}],"predecessor-version":[{"id":66208,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/tailor-covering\/66194\/revisions\/66208"}],"up":[{"embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/tailor-covering\/11566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/media\/8846"}],"wp:attachment":[{"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/media?parent=66194"}],"wp:term":[{"taxonomy":"collezione","embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/collezione?post=66194"},{"taxonomy":"linea","embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/linea?post=66194"},{"taxonomy":"materiale","embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/materiale?post=66194"},{"taxonomy":"designer","embeddable":true,"href":"https:\/\/www.momenti-casa.it\/en\/wp-json\/wp\/v2\/designer?post=66194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}